{"id":52006,"date":"2026-03-26T12:03:44","date_gmt":"2026-03-26T17:03:44","guid":{"rendered":"https:\/\/redinfor.com.pe\/portal\/?p=52006"},"modified":"2026-03-26T12:03:46","modified_gmt":"2026-03-26T17:03:46","slug":"convocatoria-de-especialista-de-monitoreo-y-evaluacion","status":"publish","type":"post","link":"https:\/\/redinfor.com.pe\/portal\/2026\/03\/26\/convocatoria-de-especialista-de-monitoreo-y-evaluacion\/","title":{"rendered":"CONVOCATORIA DE ESPECIALISTA DE MONITOREO Y EVALUACI\u00d3N"},"content":{"rendered":"\n<p class=\"has-text-align-center has-medium-font-size\"><strong>CONVOCATORIA DE ESPECIALISTA DE MONITOREO Y EVALUACI\u00d3N<\/strong><\/p>\n\n\n\n<p><strong>Objetivo de la posici\u00f3n:<\/strong>\u00a0\u00a0\u00a0<br>Dise\u00f1ar, implementar y liderar el sistema de Monitoreo, Evaluaci\u00f3n y Aprendizaje (MEAL) del proyecto Strive Woman, asegurando la medici\u00f3n rigurosa del progreso, resultados e impactos en la poblaci\u00f3n objetivo, la generaci\u00f3n de evidencia para la toma de decisiones, el aprendizaje adaptativo y la rendici\u00f3n de cuentas a donantes, socios y beneficiarios.\u00a0<\/p>\n\n\n\n<p><strong>Experiencia y Requisitos:<\/strong> <strong>&nbsp;<\/strong>&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Profesional y\/o bachiller en Econom\u00eda, Administraci\u00f3n, Ciencias Sociales, Derecho o carreras afines.<\/li>\n\n\n\n<li>M\u00ednimo 4 a\u00f1os de experiencia en organizaciones de desarrollo o proyectos similares.\u00a0<\/li>\n\n\n\n<li>Estudios de especializaci\u00f3n o maestr\u00eda en Gerencia de Proyectos Sociales, Gesti\u00f3n P\u00fablica, Derecho Laboral, G\u00e9nero o afines.<\/li>\n\n\n\n<li>Monitoreo, evaluaci\u00f3n y gesti\u00f3n financiera de programas y proyectos de desarrollo.<\/li>\n\n\n\n<li>Comprensi\u00f3n de los enfoques de desarrollo econ\u00f3mico inclusivo, gobernabilidad y derechos humanos.<\/li>\n\n\n\n<li>Conocimiento y experiencia de trabajo bajo el enfoque de g\u00e9nero.<\/li>\n\n\n\n<li>Legislaci\u00f3n laboral nacional e internacional, especialmente en trabajo del hogar y derechos de las mujeres.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:30px\"><strong><a href=\"https:\/\/drive.google.com\/file\/d\/1bZt8L7l8fWDXxUimk4EpYgE5T-QEknyi\/view?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\">VER T\u00c9RMINOS DE REFERENCIA<\/a><\/strong><\/p>\n\n\n\n<p>Las\/os interesadas\/os enviar su <strong>CV no documentado en formato PDF<\/strong> a <a href=\"mailto:rrhh@care.org.pe\">rrhh@care.org.pe<\/a> &nbsp;es importante en el ASUNTO se\u00f1alar el cargo al cu\u00e1l postula, se\u00f1alando en el Asunto: <strong>ESPECIALISTA MEL, <\/strong>fecha l\u00edmite hasta el<strong> 03 de abril del 2026<\/strong>.&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/redinfor.com.pe\/portal\/2019\/04\/24\/monitoreo-y-evaluacion-de-programas-y-proyectos-sociales\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\" https:\/\/redinfor.com.pe\/Avisos\/MEPPS\/MEPPS_advisor_large.jpg \"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CONVOCATORIA DE ESPECIALISTA DE MONITOREO Y EVALUACI\u00d3N Objetivo de la posici\u00f3n:\u00a0\u00a0\u00a0Dise\u00f1ar, implementar y liderar el sistema de Monitoreo, Evaluaci\u00f3n y Aprendizaje (MEAL) del proyecto Strive Woman, asegurando la medici\u00f3n rigurosa&hellip; <\/p>\n","protected":false},"author":1,"featured_media":19996,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[406],"tags":[139,445,607,116,494,264,4697,427,66,669,178,65,244,353,505,4699],"class_list":["post-52006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-convoca_pub","tag-administracion","tag-administrador","tag-administradora","tag-ciencias-sociales","tag-derecho","tag-economia","tag-economia-social","tag-especialista","tag-evaluacion","tag-impactos","tag-medicion","tag-monitoreo","tag-proyecto","tag-resultados","tag-sistema","tag-strive-woman"],"_links":{"self":[{"href":"https:\/\/redinfor.com.pe\/portal\/wp-json\/wp\/v2\/posts\/52006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redinfor.com.pe\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redinfor.com.pe\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redinfor.com.pe\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redinfor.com.pe\/portal\/wp-json\/wp\/v2\/comments?post=52006"}],"version-history":[{"count":1,"href":"https:\/\/redinfor.com.pe\/portal\/wp-json\/wp\/v2\/posts\/52006\/revisions"}],"predecessor-version":[{"id":52007,"href":"https:\/\/redinfor.com.pe\/portal\/wp-json\/wp\/v2\/posts\/52006\/revisions\/52007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redinfor.com.pe\/portal\/wp-json\/wp\/v2\/media\/19996"}],"wp:attachment":[{"href":"https:\/\/redinfor.com.pe\/portal\/wp-json\/wp\/v2\/media?parent=52006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redinfor.com.pe\/portal\/wp-json\/wp\/v2\/categories?post=52006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redinfor.com.pe\/portal\/wp-json\/wp\/v2\/tags?post=52006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}